{"id":11798,"date":"2026-05-17T15:13:38","date_gmt":"2026-05-17T15:13:38","guid":{"rendered":"https:\/\/energyexpo.ro\/?post_type=ee_partner&#038;p=11798"},"modified":"2026-05-17T15:13:54","modified_gmt":"2026-05-17T15:13:54","slug":"ppc-copy","status":"publish","type":"ee_partner","link":"https:\/\/energyexpo.ro\/ro\/partner\/ppc-copy\/","title":{"rendered":"PPC"},"content":{"rendered":"<section class=\"ee-partner-detail ee-partner-detail--layout-partner ee-partner-feature ee-featured-partner wp-block-ee-featured-partner\">\n    <div class=\"ee-partner-detail__container\">\n        <div class=\"ee-partner-detail__media\">\n            <div class=\"ee-partner-detail__logo-card\">\n                                    <img decoding=\"async\" src=\"https:\/\/energyexpo.ro\/wp-content\/smush-webp\/2026\/05\/ppc-energy-expo-event-logo.png.webp\" alt=\"ppc-energy-expo-event-logo\" class=\"ee-partner-detail__logo\" loading=\"lazy\" data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/energyexpo.ro\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ppc-energy-expo-event-logo.png&quot;}\">\n                            <\/div>\n\n            <a href=\"https:\/\/energyexpo.ro\/ro\/partners-sponsors\" class=\"ee-partner-detail__back-link\">\n                <span>Vezi to\u021bi partenerii \u0219i sponsorii<\/span>\n            <\/a>\n        <\/div>\n\n        <article class=\"ee-partner-detail__info-card\">\n            <div class=\"ee-partner-detail__body\">\n                <div class=\"ee-partner-detail__heading\">\n                    <h1 class=\"ee-partner-detail__name\" data-no-translation translate=\"no\">PPC<\/h1>\n                                            <span class=\"ee-partner-detail__type\">Lounge Partner<\/span>\n                                    <\/div>\n\n                                    <div class=\"ee-partner-detail__description\"><p>PPC este principala companie de energie curat\u0103 din Europa de Sud-Est, cu activit\u0103\u021bi \u00een produc\u021bia de energie electric\u0103, distribu\u021bie, operarea re\u021belelor \u0219i v\u00e2nzarea de produse \u0219i servicii energetice avansate, precum \u0219i \u00een mobilitatea electric\u0103 \u00een Grecia, Rom\u00e2nia \u0219i Macedonia de Nord. Cu o capacitate instalat\u0103 total\u0103 de 12,2GW, Grupul PPC este principalul furnizor de energie din Grecia \u0219i Rom\u00e2nia, deservind 8,8 milioane de clien\u021bi, c\u0103rora le furnizeaz\u0103 aproximativ 33 TWh de energie.<br \/>Companiile PPC din Rom\u00e2nia deservesc aproximativ 3 milioane de clien\u021bi \u00een segmentele de distribu\u021bie \u0219i furnizare de energie electric\u0103, \u00een timp ce divizia de produc\u021bie de energie din surse regenerabile are o capacitate instalat\u0103 de peste 1.330 MW. De asemenea, compania ofer\u0103 servicii de e-mobilitate \u0219i energie avansat\u0103.<br \/>PPC, fiind o companie de utilit\u0103\u021bi integrat\u0103, este bine pozi\u021bionat\u0103 pentru a conduce tranzi\u021bia energetic\u0103 \u00een regiunea Europei de Sud-Est, strategia sa concentr\u00e2ndu-se pe trei piloni principali: portofoliul de produc\u021bie de energie curat\u0103 \u0219i rezistent\u0103, modernizarea re\u021belei de distribu\u021bie \u0219i centrarea pe client. PPC a fost \u00eenfiin\u021bat\u0103 \u00een 1950 \u0219i este listat\u0103 la Bursa din Atena din 2001.<\/p>\n<\/div>\n                \n                            <\/div>\n\n                            <div class=\"ee-partner-detail__footer\">\n                                            <ul class=\"ee-partner-detail__social\">\n                                                            <li>\n                                    <a href=\"https:\/\/www.facebook.com\/ppcromaniaofficial\" class=\"ee-partner-detail__social-link ee-partner-detail__social-link--facebook\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Facebook\">\n                                        <svg viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M22 12.06C22 6.48 17.52 2 11.94 2S2 6.48 2 12.06c0 5.02 3.66 9.18 8.44 9.94v-7.03H7.9v-2.91h2.54V9.84c0-2.52 1.5-3.91 3.79-3.91 1.1 0 2.24.2 2.24.2v2.46h-1.26c-1.24 0-1.63.77-1.63 1.56v1.91h2.78l-.44 2.91h-2.34V22C18.34 21.24 22 17.08 22 12.06Z\" fill=\"currentColor\"\/><\/svg>                                    <\/a>\n                                <\/li>\n                                                            <li>\n                                    <a href=\"https:\/\/www.instagram.com\/ppcromaniaofficial\/\" class=\"ee-partner-detail__social-link ee-partner-detail__social-link--instagram\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Instagram\">\n                                        <svg viewbox=\"0 0 24 24\" aria-hidden=\"true\"><path d=\"M7.8 2h8.4A5.8 5.8 0 0 1 22 7.8v8.4a5.8 5.8 0 0 1-5.8 5.8H7.8A5.8 5.8 0 0 1 2 16.2V7.8A5.8 5.8 0 0 1 7.8 2Zm-.2 2A3.6 3.6 0 0 0 4 7.6v8.8A3.6 3.6 0 0 0 7.6 20h8.8a3.6 3.6 0 0 0 3.6-3.6V7.6A3.6 3.6 0 0 0 16.4 4H7.6Zm9.65 2.05a1.2 1.2 0 1 1 0 2.4 1.2 1.2 0 0 1 0-2.4ZM12 7.15A4.85 4.85 0 1 1 12 16.85 4.85 4.85 0 0 1 12 7.15Zm0 2A2.85 2.85 0 1 0 12 14.85 2.85 2.85 0 0 0 12 9.15Z\" fill=\"currentColor\"\/><\/svg>                                    <\/a>\n                                <\/li>\n                                                    <\/ul>\n                    \n                                            <a href=\"https:\/\/www.ppcenergy.ro\/\" class=\"ee-partner-detail__website\" target=\"_blank\" rel=\"noopener noreferrer\">\n                            <svg width=\"14\" height=\"14\" viewbox=\"0 0 14 14\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M5 9l4-4M5 5h4v4\" stroke=\"currentColor\" stroke-width=\"1.4\" fill=\"none\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg>\n                            <span>Site web<\/span>\n                        <\/a>\n                                    <\/div>\n                    <\/article>\n    <\/div>\n<\/section>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","ee_event":[33],"ee_partner_year":[45],"class_list":["post-11798","ee_partner","type-ee_partner","status-publish","hentry","ee_event-eeb"],"_links":{"self":[{"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/ee_partner\/11798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/ee_partner"}],"about":[{"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/types\/ee_partner"}],"wp:attachment":[{"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/media?parent=11798"}],"wp:term":[{"taxonomy":"ee_event","embeddable":true,"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/ee_event?post=11798"},{"taxonomy":"ee_partner_year","embeddable":true,"href":"https:\/\/energyexpo.ro\/ro\/wp-json\/wp\/v2\/ee_partner_year?post=11798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}